{"id":1313,"date":"2019-02-20T08:00:06","date_gmt":"2019-02-20T08:00:06","guid":{"rendered":"https:\/\/www.ylaios.com\/il-sentiero-perduto-limited-edition\/"},"modified":"2023-09-17T07:45:35","modified_gmt":"2023-09-17T06:45:35","slug":"il-sentiero-perduto-limited-edition","status":"publish","type":"page","link":"https:\/\/www.ylaios.com\/en\/il-sentiero-perduto-limited-edition\/","title":{"rendered":"Il sentiero perduto Limited Edition"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;89%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;89%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0|0px|27px|0px|false|false&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; header_font=&#8221;|300||||on|||&#8221; header_text_align=&#8221;center&#8221; header_2_font=&#8221;|300||||on|||&#8221; header_2_font_size=&#8221;29px&#8221; header_2_letter_spacing=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 class=\"et_pb_module_header\" style=\"text-align: center;\">Il sentiero perduto [Limited edition]<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg\" alt=\"\" class=\"wp-image-212 alignnone size-full\" style=\"display: block; margin-left: auto; margin-right: auto;\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg 950w, https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited-150x150.jpg 150w, https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited-300x300.jpg 300w, https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited-768x768.jpg 768w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|300||||on|||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;29px&#8221; header_2_letter_spacing=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">This special edition extends to only a 100 copies, each individually numbered and signed by Stefano Unterthiner. The fine print included in the work is a limited run and <em>Digigraphie<\/em> certified. The box cover is handmade in Italy.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;89%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;89%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Limited_01.jpg&#8221; show_in_lightbox=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Limited_02b.jpg&#8221; show_in_lightbox=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Limited_03.jpg&#8221; show_in_lightbox=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;89%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;89%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0|0px|27px|0px|false|false&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|300||||on|||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;29px&#8221; header_2_letter_spacing=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div style=\"text-align: center;\">Edizioni Ylaios (2015)<\/div>\n<div style=\"text-align: center;\">160 pages<\/div>\n<div style=\"text-align: center;\">95 colour photographs<\/div>\n<div style=\"text-align: center;\">Digigraphie print (29&#215;29 cm) included in the box<\/div>\n<div style=\"text-align: center;\">Text and photographs by Stefano Unterthiner<\/div>\n<div style=\"text-align: center;\">Hardback cover<\/div>\n<div style=\"text-align: center;\">Size 28,5 x 28,5 cm<\/div>\n<div style=\"text-align: center;\">Print on FSC certified paper<\/div>\n<div style=\"text-align: center;\">In Italian<\/div>\n<div style=\"text-align: center;\">ISBN\u00a0978-88-904373-4-2<\/div>\n<div style=\"text-align: center;\"><strong>Price: 180 euro (including shipping fees &#8211; EU only)<\/strong><\/div>\n<div style=\"text-align: center;\">\u00a0<\/div>\n<p style=\"text-align: center;\"><strong>Buy your copy of <em>Il sentiero perduto Limited Edition<\/em> (in Italian only)<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<div class=\"wpsc_product\"><div class=\"wp_cart_button_wrapper\"><form method=\"post\" class=\"wp-cart-button-form\" action=\"\" style=\"display:inline\" onsubmit=\"return ReadForm(this, true);\" ><input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"4bd6c94b69\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/1313\" \/><input type=\"submit\" class=\"wspsc_add_cart_submit\" name=\"wspsc_add_cart_submit\" value=\"1 copy | 180 euro\" \/><input type=\"hidden\" name=\"wspsc_product\" value=\"Il sentiero perduto Limited Edition\" \/><input type=\"hidden\" name=\"price\" value=\"180\" \/><input type=\"hidden\" name=\"shipping\" value=\"0\" \/><input type=\"hidden\" name=\"addcart\" value=\"1\" \/><input type=\"hidden\" name=\"cartLink\" value=\"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/pages\/1313\/\" \/><input type=\"hidden\" name=\"product_tmp\" value=\"Il sentiero perduto Limited Edition\" \/><input type=\"hidden\" name=\"product_tmp_two\" value=\"Il sentiero perduto Limited Edition\" \/><input type=\"hidden\" name=\"item_number\" value=\"\" \/><div class=\"wpsc_add_cart_response_div\"><\/div><\/form><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sentiero perduto [Limited edition] This special edition extends to only a 100 copies, each individually numbered and signed by Stefano Unterthiner. The fine print included in the work is a limited run and Digigraphie certified. The box cover is handmade in Italy.Edizioni Ylaios (2015) 160 pages 95 colour photographs Digigraphie print (29&#215;29 cm) included [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1313","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il sentiero perduto Limited Edition - Ylaios Edizioni<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ylaios.com\/en\/il-sentiero-perduto-limited-edition\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il sentiero perduto Limited Edition - Ylaios Edizioni\" \/>\n<meta property=\"og:description\" content=\"Il sentiero perduto [Limited edition] This special edition extends to only a 100 copies, each individually numbered and signed by Stefano Unterthiner. The fine print included in the work is a limited run and Digigraphie certified. The box cover is handmade in Italy.Edizioni Ylaios (2015) 160 pages 95 colour photographs Digigraphie print (29x29 cm) included [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Ylaios Edizioni\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-17T06:45:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/\",\"url\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/\",\"name\":\"Il sentiero perduto Limited Edition - Ylaios Edizioni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ylaios.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Cover_sentiero_limited.jpg\",\"datePublished\":\"2019-02-20T08:00:06+00:00\",\"dateModified\":\"2023-09-17T06:45:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ylaios.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Cover_sentiero_limited.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ylaios.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Cover_sentiero_limited.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/il-sentiero-perduto-limited-edition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ylaios.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il sentiero perduto Limited Edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/\",\"name\":\"Ylaios Edizioni\",\"description\":\"Ylaios Edizioni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ylaios.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il sentiero perduto Limited Edition - Ylaios Edizioni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ylaios.com\/en\/il-sentiero-perduto-limited-edition\/","og_locale":"en_US","og_type":"article","og_title":"Il sentiero perduto Limited Edition - Ylaios Edizioni","og_description":"Il sentiero perduto [Limited edition] This special edition extends to only a 100 copies, each individually numbered and signed by Stefano Unterthiner. The fine print included in the work is a limited run and Digigraphie certified. The box cover is handmade in Italy.Edizioni Ylaios (2015) 160 pages 95 colour photographs Digigraphie print (29x29 cm) included [&hellip;]","og_url":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/","og_site_name":"Ylaios Edizioni","article_modified_time":"2023-09-17T06:45:35+00:00","og_image":[{"url":"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/","url":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/","name":"Il sentiero perduto Limited Edition - Ylaios Edizioni","isPartOf":{"@id":"https:\/\/www.ylaios.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/#primaryimage"},"image":{"@id":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg","datePublished":"2019-02-20T08:00:06+00:00","dateModified":"2023-09-17T06:45:35+00:00","breadcrumb":{"@id":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/#primaryimage","url":"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg","contentUrl":"https:\/\/www.ylaios.com\/wp-content\/uploads\/2018\/12\/Cover_sentiero_limited.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ylaios.com\/it\/il-sentiero-perduto-limited-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ylaios.com\/en\/"},{"@type":"ListItem","position":2,"name":"Il sentiero perduto Limited Edition"}]},{"@type":"WebSite","@id":"https:\/\/www.ylaios.com\/it\/#website","url":"https:\/\/www.ylaios.com\/it\/","name":"Ylaios Edizioni","description":"Ylaios Edizioni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ylaios.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/pages\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":9,"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/pages\/1313\/revisions"}],"predecessor-version":[{"id":3709,"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/pages\/1313\/revisions\/3709"}],"wp:attachment":[{"href":"https:\/\/www.ylaios.com\/en\/wp-json\/wp\/v2\/media?parent=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}